{"id":17074,"date":"2024-11-13T18:45:06","date_gmt":"2024-11-13T16:45:06","guid":{"rendered":"https:\/\/masterbase.com\/es\/es\/es\/es\/?page_id=17074"},"modified":"2025-07-29T19:36:36","modified_gmt":"2025-07-29T16:36:36","slug":"uzsako-jo-sukurima","status":"publish","type":"page","link":"https:\/\/masterbase.com\/lt\/mb\/crea-soluciones\/que-puedes-crear\/encarga-su-creacion\/","title":{"rendered":"Paveda j\u0105 sukurti."},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"17074\" class=\"elementor elementor-17074\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9088709 elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"9088709\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4bd1ce9 e-con-full e-flex e-con e-child\" data-id=\"4bd1ce9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-abd752c e-con-full e-flex e-con e-child\" data-id=\"abd752c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ccd5a76 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"ccd5a76\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" data-attachment-id=\"20061\" data-permalink=\"https:\/\/masterbase.com\/lt\/mb\/usa-soluciones\/automata-comb-3-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2025\/01\/automata-comb-3-1.png?fit=545%2C545&amp;ssl=1\" data-orig-size=\"545,545\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Encarga su creaci\u00f3n\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2025\/01\/automata-comb-3-1.png?fit=545%2C545&amp;ssl=1\" width=\"545\" height=\"545\" src=\"https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2025\/01\/automata-comb-3-1.png?fit=545%2C545&amp;ssl=1\" class=\"attachment-large size-large wp-image-20061\" alt=\"Paveda j\u0105 sukurti.\" srcset=\"https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2025\/01\/automata-comb-3-1.png?w=545&amp;ssl=1 545w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2025\/01\/automata-comb-3-1.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2025\/01\/automata-comb-3-1.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2025\/01\/automata-comb-3-1.png?resize=12%2C12&amp;ssl=1 12w\" sizes=\"(max-width: 545px) 100vw, 545px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-90670be elementor-widget elementor-widget-spacer\" data-id=\"90670be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e9bcf16 elementor-widget elementor-widget-heading\" data-id=\"e9bcf16\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Komisiniai mokes\u010diai\njos suk\u016brimas<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-710fbea elementor-widget elementor-widget-text-editor\" data-id=\"710fbea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"col-12 col-lg-8 d-flex justify-content-center order-sm-2 order-lg-1 align-items-start flex-column\"><div class=\"container\"><h2 class=\"titleText\">Patik\u0117kite automatizuot\u0173 sprendim\u0173 k\u016brim\u0105 ekspertui konsultantui.<\/h2><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-341af65 e-flex e-con-boxed e-con e-child\" data-id=\"341af65\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-79e33b0 elementor-mobile-align-center elementor-widget__width-initial elementor-align-center elementor-widget elementor-widget-button\" data-id=\"79e33b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/lt\/lp-kontaktinis-vadovas\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-double-right\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34zm192-34l-136-136c-9.4-9.4-24.6-9.4-33.9 0l-22.6 22.6c-9.4 9.4-9.4 24.6 0 33.9l96.4 96.4-96.4 96.4c-9.4 9.4-9.4 24.6 0 33.9l22.6 22.6c9.4 9.4 24.6 9.4 33.9 0l136-136c9.4-9.2 9.4-24.4 0-33.8z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Susisiekite su vadovu<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c8874f1 elementor-widget elementor-widget-image\" data-id=\"c8874f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/publicsmartview.masterbase.com\/v1\/67658f2bbbd8240ddb2b6f3a\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" data-attachment-id=\"900\" data-permalink=\"https:\/\/masterbase.com\/lt\/?attachment_id=900\" data-orig-file=\"https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2023\/09\/video_overall_theme03.png?fit=752%2C626&amp;ssl=1\" data-orig-size=\"752,626\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"video_overall_theme03\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2023\/09\/video_overall_theme03.png?fit=752%2C626&amp;ssl=1\" width=\"752\" height=\"626\" src=\"https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2023\/09\/video_overall_theme03.png?fit=752%2C626&amp;ssl=1\" class=\"attachment-large size-large wp-image-900\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2023\/09\/video_overall_theme03.png?w=752&amp;ssl=1 752w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2023\/09\/video_overall_theme03.png?resize=300%2C250&amp;ssl=1 300w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2023\/09\/video_overall_theme03.png?resize=600%2C499&amp;ssl=1 600w\" sizes=\"(max-width: 752px) 100vw, 752px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1a87ddc e-con-full e-flex e-con e-child\" data-id=\"1a87ddc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-12814b8 elementor-widget elementor-widget-image\" data-id=\"12814b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" data-attachment-id=\"17003\" data-permalink=\"https:\/\/masterbase.com\/lt\/mb\/encarga-su-creacion-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/11\/Encarga-su-creacion.png?fit=2744%2C1830&amp;ssl=1\" data-orig-size=\"2744,1830\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"MBE\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/11\/Encarga-su-creacion.png?fit=800%2C534&amp;ssl=1\" width=\"800\" height=\"534\" src=\"https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/11\/Encarga-su-creacion.png?fit=800%2C534&amp;ssl=1\" class=\"attachment-large size-large wp-image-17003\" alt=\"MBE\" srcset=\"https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/11\/Encarga-su-creacion.png?w=2744&amp;ssl=1 2744w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/11\/Encarga-su-creacion.png?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/11\/Encarga-su-creacion.png?resize=1024%2C683&amp;ssl=1 1024w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/11\/Encarga-su-creacion.png?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/11\/Encarga-su-creacion.png?resize=1536%2C1024&amp;ssl=1 1536w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/11\/Encarga-su-creacion.png?resize=2048%2C1366&amp;ssl=1 2048w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/11\/Encarga-su-creacion.png?resize=18%2C12&amp;ssl=1 18w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/11\/Encarga-su-creacion.png?w=1600&amp;ssl=1 1600w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/11\/Encarga-su-creacion.png?w=2400&amp;ssl=1 2400w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-74a5f1b elementor-hidden-desktop e-flex e-con-boxed e-con e-parent\" data-id=\"74a5f1b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-47dd2c1 elementor-widget elementor-widget-image\" data-id=\"47dd2c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/staging-e1b8-masterbasecom.wpcomstaging.com\/wp-content\/uploads\/2024\/11\/76.png?w=800&#038;ssl=1\" title=\"\" alt=\"Paveda j\u0105 sukurti.\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e966acc elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget elementor-widget-heading\" data-id=\"e966acc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-small\">Komisiniai mokes\u010diai\njos suk\u016brimas\n<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-72ede18 elementor-widget elementor-widget-spacer\" data-id=\"72ede18\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-af74afd elementor-widget elementor-widget-image\" data-id=\"af74afd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" data-attachment-id=\"17003\" data-permalink=\"https:\/\/masterbase.com\/lt\/mb\/encarga-su-creacion-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/11\/Encarga-su-creacion.png?fit=2744%2C1830&amp;ssl=1\" data-orig-size=\"2744,1830\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"MBE\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/11\/Encarga-su-creacion.png?fit=800%2C534&amp;ssl=1\" width=\"800\" height=\"534\" src=\"https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/11\/Encarga-su-creacion.png?fit=800%2C534&amp;ssl=1\" class=\"attachment-large size-large wp-image-17003\" alt=\"MBE\" srcset=\"https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/11\/Encarga-su-creacion.png?w=2744&amp;ssl=1 2744w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/11\/Encarga-su-creacion.png?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/11\/Encarga-su-creacion.png?resize=1024%2C683&amp;ssl=1 1024w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/11\/Encarga-su-creacion.png?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/11\/Encarga-su-creacion.png?resize=1536%2C1024&amp;ssl=1 1536w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/11\/Encarga-su-creacion.png?resize=2048%2C1366&amp;ssl=1 2048w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/11\/Encarga-su-creacion.png?resize=18%2C12&amp;ssl=1 18w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/11\/Encarga-su-creacion.png?w=1600&amp;ssl=1 1600w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/11\/Encarga-su-creacion.png?w=2400&amp;ssl=1 2400w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e0b3199 elementor-widget elementor-widget-spacer\" data-id=\"e0b3199\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f574360 elementor-widget elementor-widget-spacer\" data-id=\"f574360\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0d9bc1d elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"0d9bc1d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Patik\u0117kite automatizuot\u0173 sprendim\u0173 k\u016brim\u0105 ekspertui konsultantui.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a637cab elementor-mobile-align-center elementor-widget__width-initial elementor-align-center elementor-widget elementor-widget-button\" data-id=\"a637cab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/contactoejecutivo.masterbase.com\/#contacta\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-double-right\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34zm192-34l-136-136c-9.4-9.4-24.6-9.4-33.9 0l-22.6 22.6c-9.4 9.4-9.4 24.6 0 33.9l96.4 96.4-96.4 96.4c-9.4 9.4-9.4 24.6 0 33.9l22.6 22.6c9.4 9.4 24.6 9.4 33.9 0l136-136c9.4-9.2 9.4-24.4 0-33.8z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Susisiekite su vadovu <\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bf25682 elementor-widget elementor-widget-spacer\" data-id=\"bf25682\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1223781 elementor-widget elementor-widget-image\" data-id=\"1223781\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/publicsmartview.masterbase.com\/v1\/657b43ec5bcbbd04619c98b1\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"900\" data-permalink=\"https:\/\/masterbase.com\/lt\/?attachment_id=900\" data-orig-file=\"https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2023\/09\/video_overall_theme03.png?fit=752%2C626&amp;ssl=1\" data-orig-size=\"752,626\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"video_overall_theme03\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2023\/09\/video_overall_theme03.png?fit=752%2C626&amp;ssl=1\" width=\"300\" height=\"250\" src=\"https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2023\/09\/video_overall_theme03.png?fit=300%2C250&amp;ssl=1\" class=\"attachment-medium size-medium wp-image-900\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2023\/09\/video_overall_theme03.png?w=752&amp;ssl=1 752w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2023\/09\/video_overall_theme03.png?resize=300%2C250&amp;ssl=1 300w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2023\/09\/video_overall_theme03.png?resize=600%2C499&amp;ssl=1 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27e0a71 elementor-widget elementor-widget-spacer\" data-id=\"27e0a71\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-12f9173 e-flex e-con-boxed e-con e-parent\" data-id=\"12f9173\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ae0607c e-flex e-con-boxed e-con e-child\" data-id=\"ae0607c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-37f4bb1 elementor-widget elementor-widget-spacer\" data-id=\"37f4bb1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aecd4a6 elementor-widget elementor-widget-heading\" data-id=\"aecd4a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Komisiniai mokes\u010diai\njos suk\u016brimas\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c517e8b elementor-widget elementor-widget-heading\" data-id=\"c517e8b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Optimizuokite savo versl\u0105 perduodami automatizavim\u0105 m\u016bs\u0173 \"Flex Consulting\" ekspertams.\n<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-00f7ddb elementor-widget elementor-widget-heading\" data-id=\"00f7ddb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Nuolat besikei\u010dian\u010dioje verslo aplinkoje \"Flex Consulting\" si\u016blo i\u0161sam\u0173 sprendim\u0105, leid\u017eiant\u012f automatizuot\u0173 proces\u0173 \u012fgyvendinim\u0105 patik\u0117ti auk\u0161tos kvalifikacijos konsultantui. <\/p>\n\nM\u016bs\u0173 ekspertai ne tik kuria sprendimus, bet ir u\u017etikrina j\u0173 integravim\u0105 bei optimal\u0173 veikim\u0105, pritaikydami juos prie kiekvieno asmens ir (arba) \u012fmon\u0117s ypatum\u0173.\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d7985f3 e-flex e-con-boxed e-con e-parent\" data-id=\"d7985f3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bd255f6 elementor-widget elementor-widget-spacer\" data-id=\"bd255f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f14ec7d e-flex e-con-boxed e-con e-child\" data-id=\"f14ec7d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4b0b1f1 e-con-full e-flex e-con e-child\" data-id=\"4b0b1f1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b6bc1de elementor-widget elementor-widget-spacer\" data-id=\"b6bc1de\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-db269c4 elementor-widget elementor-widget-image\" data-id=\"db269c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"17325\" data-permalink=\"https:\/\/masterbase.com\/lt\/mb\/crea-soluciones\/que-puedes-crear\/encarga-su-creacion\/graficas-07\/\" data-orig-file=\"https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/11\/graficas-07.png?fit=820%2C580&amp;ssl=1\" data-orig-size=\"820,580\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Flex Consulting\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/11\/graficas-07.png?fit=800%2C566&amp;ssl=1\" width=\"800\" height=\"566\" src=\"https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/11\/graficas-07.png?fit=800%2C566&amp;ssl=1\" class=\"attachment-large size-large wp-image-17325\" alt=\"&quot;Flex Consulting\" srcset=\"https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/11\/graficas-07.png?w=820&amp;ssl=1 820w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/11\/graficas-07.png?resize=300%2C212&amp;ssl=1 300w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/11\/graficas-07.png?resize=768%2C543&amp;ssl=1 768w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/11\/graficas-07.png?resize=18%2C12&amp;ssl=1 18w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-872391a e-con-full e-flex e-con e-child\" data-id=\"872391a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-cb5c8d8 e-flex e-con-boxed e-con e-child\" data-id=\"cb5c8d8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d3099f3 elementor-widget elementor-widget-spacer\" data-id=\"d3099f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1015621 e-flex e-con-boxed e-con e-child\" data-id=\"1015621\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e5bb404 elementor-widget elementor-widget-heading\" data-id=\"e5bb404\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">K\u0105 \"Flex Consulting\" si\u016blo proces\u0173 automatizavimo srityje?\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-49c576b elementor-widget elementor-widget-text-editor\" data-id=\"49c576b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Proces\u0173 automatizavimas - tai daugiau nei tiesiog \u012fdiegti \u012frank\u012f ir tik\u0117tis, kad jis veiks.<\/p><p>Kad automatizavimas b\u016bt\u0173 veiksmingas, reikia gerai i\u0161manyti savo veikl\u0105 ir kruop\u0161\u010diai pritaikyti j\u0105 konkretiems poreikiams. B\u016btent \u010dia \"Flex Consulting\" yra prana\u0161esn\u0117:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b7f8949 e-flex e-con-boxed e-con e-parent\" data-id=\"b7f8949\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6d96d56 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"6d96d56\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"2252\" data-permalink=\"https:\/\/masterbase.com\/lt\/imagenes-3\/\" data-orig-file=\"https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2023\/10\/imagenes-3.png?fit=484%2C516&amp;ssl=1\" data-orig-size=\"484,516\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Automation Solution Ideas\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2023\/10\/imagenes-3.png?fit=484%2C516&amp;ssl=1\" width=\"484\" height=\"516\" src=\"https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2023\/10\/imagenes-3.png?fit=484%2C516&amp;ssl=1\" class=\"attachment-large size-large wp-image-2252\" alt=\"Automatizavimo sprendim\u0173 id\u0117jos\" srcset=\"https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2023\/10\/imagenes-3.png?w=484&amp;ssl=1 484w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2023\/10\/imagenes-3.png?resize=281%2C300&amp;ssl=1 281w\" sizes=\"(max-width: 484px) 100vw, 484px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fbc4351 elementor-widget elementor-widget-spacer\" data-id=\"fbc4351\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5e7c363 e-con-full e-flex e-con e-child\" data-id=\"5e7c363\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bcfbbf7 elementor-widget elementor-widget-heading\" data-id=\"bcfbbf7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">1. Atradimas<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ec1208 elementor-widget elementor-widget-spacer\" data-id=\"2ec1208\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0bea786 elementor-widget elementor-widget-heading\" data-id=\"0bea786\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Analizuojame j\u016bs\u0173 dabartinius procesus ir automatizavimo tikslus, nustatome pagrindines sritis, kuriose galima padidinti efektyvum\u0105 ir suma\u017einti s\u0105naudas.\n\nPirmajame etape analizuojame j\u016bs\u0173 dabartinius procesus ir automatizavimo tikslus. <br> <br>\u010cia nurodysime sritis, kuriose galite padidinti efektyvum\u0105 ir suma\u017einti i\u0161laidas. \u0160is i\u0161samios analiz\u0117s etapas yra labai svarbus siekiant u\u017etikrinti, kad automatizavimo pastangos b\u016bt\u0173 sutelktos \u012f tuos aspektus, kurie i\u0161 tikr\u0173j\u0173 pakeis j\u016bs\u0173 veikl\u0105.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a9922e3 e-flex e-con-boxed e-con e-parent\" data-id=\"a9922e3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fa91487 elementor-widget elementor-widget-spacer\" data-id=\"fa91487\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9403586 e-flex e-con-boxed e-con e-parent\" data-id=\"9403586\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-360d2e4 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"360d2e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"14984\" data-permalink=\"https:\/\/masterbase.com\/lt\/seguridad-en-la-nube-mitigar-riesgos-en-infraestructuras-cloud\/masterbase\/3-1-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/06\/3-1.png?fit=1500%2C1500&amp;ssl=1\" data-orig-size=\"1500,1500\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Seguridad en la nube\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Seguridad en la nube&lt;\/p&gt;\" data-large-file=\"https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/06\/3-1.png?fit=800%2C800&amp;ssl=1\" width=\"800\" height=\"800\" src=\"https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/06\/3-1.png?fit=800%2C800&amp;ssl=1\" class=\"attachment-large size-large wp-image-14984\" alt=\"Debes\u0173 saugumas\" srcset=\"https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/06\/3-1.png?w=1500&amp;ssl=1 1500w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/06\/3-1.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/06\/3-1.png?resize=1024%2C1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/06\/3-1.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/06\/3-1.png?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/06\/3-1.png?resize=12%2C12&amp;ssl=1 12w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/06\/3-1.png?resize=1200%2C1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/06\/3-1.png?resize=800%2C800&amp;ssl=1 800w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/06\/3-1.png?resize=600%2C600&amp;ssl=1 600w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/06\/3-1.png?resize=400%2C400&amp;ssl=1 400w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/06\/3-1.png?resize=200%2C200&amp;ssl=1 200w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fd55e4b elementor-widget elementor-widget-spacer\" data-id=\"fd55e4b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-627d535 e-con-full e-flex e-con e-child\" data-id=\"627d535\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-48ba75a elementor-widget elementor-widget-heading\" data-id=\"48ba75a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">2. Pagrindini\u0173 proces\u0173 nustatymas: <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d6c26ff elementor-widget elementor-widget-spacer\" data-id=\"d6c26ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c5e45eb elementor-widget elementor-widget-heading\" data-id=\"c5e45eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">D\u0117mes\u012f sutelkiame \u012f galimybes, kurios maksimaliai padidina poveik\u012f ir investicij\u0173 gr\u0105\u017e\u0105.<br><br>\n\nRemdamiesi analize, m\u016bs\u0173 konsultantai nustato svarbiausius procesus, kuriuos galima optimizuoti automatizuojant. <br><br>\n\nDaugiausia d\u0117mesio skiriame toms sritims, kurios tur\u0117s did\u017eiausi\u0105 poveik\u012f j\u016bs\u0173 verslui ir kurios gali greitai ir reik\u0161mingai atsipirkti.<br><br>\n\n\u0160is strateginis po\u017ei\u016bris u\u017etikrina, kad \u012f automatizavim\u0105 investuotos pastangos ir i\u0161tekliai duot\u0173 geriausius \u012fmanomus rezultatus.\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f6208b4 e-flex e-con-boxed e-con e-parent\" data-id=\"f6208b4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3c5d490 elementor-widget elementor-widget-spacer\" data-id=\"3c5d490\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3adf84d e-flex e-con-boxed e-con e-parent\" data-id=\"3adf84d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-839ce7a elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"839ce7a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"16668\" data-permalink=\"https:\/\/masterbase.com\/lt\/como-la-automatizacion-de-procesos-revoluciona-la-gestion-de-inventarios\/masterbase\/1-8\/\" data-orig-file=\"https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/09\/1-1.png?fit=2250%2C2250&amp;ssl=1\" data-orig-size=\"2250,2250\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Inventario automatizado\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/09\/1-1.png?fit=800%2C800&amp;ssl=1\" width=\"800\" height=\"800\" src=\"https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/09\/1-1.png?fit=800%2C800&amp;ssl=1\" class=\"attachment-large size-large wp-image-16668\" alt=\"Automatizuota inventorizacija\" srcset=\"https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/09\/1-1.png?w=2250&amp;ssl=1 2250w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/09\/1-1.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/09\/1-1.png?resize=1024%2C1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/09\/1-1.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/09\/1-1.png?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/09\/1-1.png?resize=1536%2C1536&amp;ssl=1 1536w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/09\/1-1.png?resize=2048%2C2048&amp;ssl=1 2048w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/09\/1-1.png?resize=12%2C12&amp;ssl=1 12w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/09\/1-1.png?w=1600&amp;ssl=1 1600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ea6f14 elementor-widget elementor-widget-spacer\" data-id=\"1ea6f14\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6b170de e-con-full e-flex e-con e-child\" data-id=\"6b170de\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3ae6e49 elementor-widget elementor-widget-heading\" data-id=\"3ae6e49\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">3. I\u0161samus dizaino pasi\u016blymas: <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ff5a4b5 elementor-widget elementor-widget-spacer\" data-id=\"ff5a4b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb16e4f elementor-widget elementor-widget-heading\" data-id=\"bb16e4f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Sukuriame ir tobuliname veiksm\u0173 plan\u0105, suderint\u0105 su nustatytais tikslais.<br><br>\n\nRemdamiesi surinkta informacija, parengiame i\u0161sam\u0173 veiksm\u0173 plan\u0105. \u0160is planas apima konkret\u0173 pasi\u016blym\u0105, kuriame paai\u0161kinama, kaip atrodys automatizuoti procesai ir kaip jie veiks kartu su kitomis j\u016bs\u0173 veiklos sritimis. <br><br>\n\nU\u017etikriname, kad \u0161is planas b\u016bt\u0173 suderintas su atradimo etape nustatytais tikslais ir kad jis atitikt\u0173 turimus i\u0161teklius.\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-90c68bb e-flex e-con-boxed e-con e-parent\" data-id=\"90c68bb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a59a718 elementor-widget elementor-widget-spacer\" data-id=\"a59a718\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-701be85 e-flex e-con-boxed e-con e-parent\" data-id=\"701be85\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-85580bd elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"85580bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"16165\" data-permalink=\"https:\/\/masterbase.com\/lt\/10-formas-tacticas-para-re-encantar-a-tus-contactos-inactivos\/masterbase\/2-6\/\" data-orig-file=\"https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/09\/2.png?fit=2250%2C2250&amp;ssl=1\" data-orig-size=\"2250,2250\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"email relevancia\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/09\/2.png?fit=800%2C800&amp;ssl=1\" width=\"800\" height=\"800\" src=\"https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/09\/2.png?fit=800%2C800&amp;ssl=1\" class=\"attachment-large size-large wp-image-16165\" alt=\"el. pa\u0161to aktualumas\" srcset=\"https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/09\/2.png?w=2250&amp;ssl=1 2250w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/09\/2.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/09\/2.png?resize=1024%2C1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/09\/2.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/09\/2.png?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/09\/2.png?resize=1536%2C1536&amp;ssl=1 1536w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/09\/2.png?resize=2048%2C2048&amp;ssl=1 2048w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/09\/2.png?resize=12%2C12&amp;ssl=1 12w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/09\/2.png?w=1600&amp;ssl=1 1600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-196c75d elementor-widget elementor-widget-spacer\" data-id=\"196c75d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-44c9c5b e-con-full e-flex e-con e-child\" data-id=\"44c9c5b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a44d95f elementor-widget elementor-widget-heading\" data-id=\"a44d95f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">4. Specialiai pritaikytas \u012fgyvendinimas: <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f76ea62 elementor-widget elementor-widget-spacer\" data-id=\"f76ea62\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ac3c9ff elementor-widget elementor-widget-heading\" data-id=\"ac3c9ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Konfig\u016bruojame ir pritaikome konkre\u010dius sprendimus, u\u017etikrindami skland\u017ei\u0105 ir operatyvi\u0105 integracij\u0105.<br><br>\n\nDiegimo etape m\u016bs\u0173 \"Flex Consulting\" komanda sukonfig\u016bruoja ir pritaiko sprendimus konkre\u010dioms j\u016bs\u0173 sistemoms, u\u017etikrindama skland\u017ei\u0105 integracij\u0105 ir skland\u0173 veikim\u0105. <br><br>\n\nKiekvienas automatizavimo aspektas i\u0161bandomas ir derinamas, kad atitikt\u0173 l\u016bkes\u010dius ir gerai veikt\u0173 j\u016bs\u0173 verslo kontekste.\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d7c3e73 e-flex e-con-boxed e-con e-child\" data-id=\"d7c3e73\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-caba84f e-con-full e-flex e-con e-child\" data-id=\"caba84f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3db3a24 elementor-widget elementor-widget-spacer\" data-id=\"3db3a24\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-500bf94 elementor-widget elementor-widget-image\" data-id=\"500bf94\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"17324\" data-permalink=\"https:\/\/masterbase.com\/lt\/mb\/crea-soluciones\/que-puedes-crear\/encarga-su-creacion\/graficas-05\/\" data-orig-file=\"https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/11\/graficas-05.png?fit=820%2C580&amp;ssl=1\" data-orig-size=\"820,580\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Flex Consulting\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/11\/graficas-05.png?fit=800%2C566&amp;ssl=1\" width=\"800\" height=\"566\" src=\"https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/11\/graficas-05.png?fit=800%2C566&amp;ssl=1\" class=\"attachment-large size-large wp-image-17324\" alt=\"&quot;Flex Consulting\" srcset=\"https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/11\/graficas-05.png?w=820&amp;ssl=1 820w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/11\/graficas-05.png?resize=300%2C212&amp;ssl=1 300w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/11\/graficas-05.png?resize=768%2C543&amp;ssl=1 768w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/11\/graficas-05.png?resize=18%2C12&amp;ssl=1 18w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-54b0087 e-con-full e-flex e-con e-child\" data-id=\"54b0087\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-43182e8 e-flex e-con-boxed e-con e-child\" data-id=\"43182e8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-747a9ec elementor-widget elementor-widget-spacer\" data-id=\"747a9ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-beafaf1 e-flex e-con-boxed e-con e-child\" data-id=\"beafaf1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d022b23 elementor-widget elementor-widget-heading\" data-id=\"d022b23\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Kod\u0117l tur\u0117tum\u0117te apsvarstyti \"Flex Consulting\"?\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d35ecb7 elementor-widget elementor-widget-text-editor\" data-id=\"d35ecb7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Jei svarstote apie proces\u0173 automatizavim\u0105, bet ne\u017einote, kaip prad\u0117ti, arba tiesiog neturite laiko ar technini\u0173 \u017eini\u0173, \"Flex Consulting\" gali pad\u0117ti.<\/p><p>M\u016bs\u0173 konsultacijos yra idealus sprendimas, padedantis efektyviai \u012fdiegti automatizavim\u0105.<\/p><p>Eksperto, kuris jums pad\u0117s kiekviename \u017eingsnyje, privalumai yra nesuskai\u010diuojami:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6000b95 e-flex e-con-boxed e-con e-parent\" data-id=\"6000b95\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7bb752f elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"7bb752f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"7004\" data-permalink=\"https:\/\/masterbase.com\/lt\/conoce-todo-el-potencial-de-la-herramienta-math-y-sacale-provecho-en-tus-soluciones\/masterbase\/herramienta3\/\" data-orig-file=\"https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2023\/12\/herramienta3.png?fit=4269%2C3781&amp;ssl=1\" data-orig-size=\"4269,3781\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"herramienta3\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2023\/12\/herramienta3.png?fit=800%2C709&amp;ssl=1\" width=\"800\" height=\"709\" src=\"https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2023\/12\/herramienta3.png?fit=800%2C709&amp;ssl=1\" class=\"attachment-large size-large wp-image-7004\" alt=\"\u012frankis3\" srcset=\"https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2023\/12\/herramienta3.png?w=4269&amp;ssl=1 4269w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2023\/12\/herramienta3.png?resize=300%2C266&amp;ssl=1 300w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2023\/12\/herramienta3.png?resize=1024%2C907&amp;ssl=1 1024w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2023\/12\/herramienta3.png?resize=768%2C680&amp;ssl=1 768w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2023\/12\/herramienta3.png?resize=1536%2C1360&amp;ssl=1 1536w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2023\/12\/herramienta3.png?resize=2048%2C1814&amp;ssl=1 2048w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2023\/12\/herramienta3.png?resize=14%2C12&amp;ssl=1 14w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2023\/12\/herramienta3.png?w=1600&amp;ssl=1 1600w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2023\/12\/herramienta3.png?w=2400&amp;ssl=1 2400w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-980cb70 elementor-widget elementor-widget-spacer\" data-id=\"980cb70\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-910468e e-con-full e-flex e-con e-child\" data-id=\"910468e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a00e6b5 elementor-widget elementor-widget-heading\" data-id=\"a00e6b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Taupomas laikas ir i\u0161tekliai: \n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-39645c1 elementor-widget elementor-widget-spacer\" data-id=\"39645c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f59f90 elementor-widget elementor-widget-heading\" data-id=\"1f59f90\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Perduodami automatizavim\u0105 \"Flex Consulting\" konsultantui, galite sutelkti d\u0117mes\u012f \u012f kitas svarbias savo verslo sritis, o ekspertai pasir\u016bpins techniniu procesu.\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b756595 e-flex e-con-boxed e-con e-parent\" data-id=\"b756595\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2d865f2 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"2d865f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"10617\" data-permalink=\"https:\/\/masterbase.com\/lt\/mb\/portal_clientes\/ilu4-3\/\" data-orig-file=\"https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/02\/ilu4.png?fit=6000%2C3400&amp;ssl=1\" data-orig-size=\"6000,3400\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"On Boarding\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/02\/ilu4.png?fit=800%2C453&amp;ssl=1\" width=\"800\" height=\"453\" src=\"https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/02\/ilu4.png?fit=800%2C453&amp;ssl=1\" class=\"attachment-large size-large wp-image-10617\" alt=\"\u012elaipinimo metu\" srcset=\"https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/02\/ilu4.png?w=6000&amp;ssl=1 6000w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/02\/ilu4.png?resize=300%2C170&amp;ssl=1 300w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/02\/ilu4.png?resize=1024%2C580&amp;ssl=1 1024w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/02\/ilu4.png?resize=768%2C435&amp;ssl=1 768w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/02\/ilu4.png?resize=1536%2C870&amp;ssl=1 1536w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/02\/ilu4.png?resize=2048%2C1161&amp;ssl=1 2048w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/02\/ilu4.png?resize=18%2C10&amp;ssl=1 18w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/02\/ilu4.png?w=1600&amp;ssl=1 1600w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/02\/ilu4.png?w=2400&amp;ssl=1 2400w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5309779 elementor-widget elementor-widget-spacer\" data-id=\"5309779\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d10c775 e-con-full e-flex e-con e-child\" data-id=\"d10c775\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5cf5adb elementor-widget elementor-widget-heading\" data-id=\"5cf5adb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Individual\u016bs sprendimai: \n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0f69670 elementor-widget elementor-widget-spacer\" data-id=\"0f69670\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-91c3058 elementor-widget elementor-widget-heading\" data-id=\"91c3058\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">U\u017euot naudoj\u0119si bendru \u0161ablonu, gausite konkret\u0173 sprendim\u0105, atitinkant\u012f j\u016bs\u0173 poreikius ir pritaikyt\u0105 j\u016bs\u0173 \u012fmonei.\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-eae7bda e-flex e-con-boxed e-con e-parent\" data-id=\"eae7bda\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d92c670 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"d92c670\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"7086\" data-permalink=\"https:\/\/masterbase.com\/lt\/5-formas-de-aprovechar-la-automatizacion-en-el-lugar-de-trabajo\/masterbase\/automatiza-1\/\" data-orig-file=\"https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2023\/12\/automatiza-1.png?fit=1075%2C955&amp;ssl=1\" data-orig-size=\"1075,955\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"email marketing\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2023\/12\/automatiza-1.png?fit=800%2C711&amp;ssl=1\" width=\"800\" height=\"711\" src=\"https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2023\/12\/automatiza-1.png?fit=800%2C711&amp;ssl=1\" class=\"attachment-large size-large wp-image-7086\" alt=\"el. pa\u0161to rinkodara\" srcset=\"https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2023\/12\/automatiza-1.png?w=1075&amp;ssl=1 1075w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2023\/12\/automatiza-1.png?resize=300%2C267&amp;ssl=1 300w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2023\/12\/automatiza-1.png?resize=1024%2C910&amp;ssl=1 1024w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2023\/12\/automatiza-1.png?resize=768%2C682&amp;ssl=1 768w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2023\/12\/automatiza-1.png?resize=14%2C12&amp;ssl=1 14w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-32cc180 elementor-widget elementor-widget-spacer\" data-id=\"32cc180\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9c1136e e-con-full e-flex e-con e-child\" data-id=\"9c1136e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1c35871 elementor-widget elementor-widget-heading\" data-id=\"1c35871\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Klaid\u0173 ir rizikos ma\u017einimas: \n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9969fa7 elementor-widget elementor-widget-spacer\" data-id=\"9969fa7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-79803bf elementor-widget elementor-widget-heading\" data-id=\"79803bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">M\u016bs\u0173 konsultantai u\u017etikrina, kad diegimo procesas vykt\u0173 be klaid\u0173, tod\u0117l suma\u017e\u0117ja trikd\u017ei\u0173 ar veiklos sutrikim\u0173 rizika.\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ab3fa0a e-flex e-con-boxed e-con e-parent\" data-id=\"ab3fa0a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f3cc6b7 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"f3cc6b7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"7022\" data-permalink=\"https:\/\/masterbase.com\/lt\/da-vida-a-tus-access-points-usando-automatas-ondemand\/masterbase\/3-1\/\" data-orig-file=\"https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2023\/12\/3-1.png?fit=1146%2C922&amp;ssl=1\" data-orig-size=\"1146,922\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"MasterBase Labs\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2023\/12\/3-1.png?fit=800%2C644&amp;ssl=1\" width=\"800\" height=\"644\" src=\"https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2023\/12\/3-1.png?fit=800%2C644&amp;ssl=1\" class=\"attachment-large size-large wp-image-7022\" alt=\"MasterBase laboratorijos\" srcset=\"https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2023\/12\/3-1.png?w=1146&amp;ssl=1 1146w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2023\/12\/3-1.png?resize=300%2C241&amp;ssl=1 300w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2023\/12\/3-1.png?resize=1024%2C824&amp;ssl=1 1024w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2023\/12\/3-1.png?resize=768%2C618&amp;ssl=1 768w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2023\/12\/3-1.png?resize=15%2C12&amp;ssl=1 15w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f8eddb4 elementor-widget elementor-widget-spacer\" data-id=\"f8eddb4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d31921b e-con-full e-flex e-con e-child\" data-id=\"d31921b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0a4cec4 elementor-widget elementor-widget-heading\" data-id=\"0a4cec4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Prisitaikymas prie nauj\u0173 tendencij\u0173: \n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-721e7d5 elementor-widget elementor-widget-spacer\" data-id=\"721e7d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-83da75f elementor-widget elementor-widget-heading\" data-id=\"83da75f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Technologijos spar\u010diai tobul\u0117ja, tod\u0117l \"Flex Consulting\" komanda u\u017etikrina, kad m\u016bs\u0173 diegiamus sprendimus b\u016bt\u0173 galima atnaujinti ir jie b\u016bt\u0173 suderinami su naujomis automatizavimo priemon\u0117mis, kurios gali atsirasti ateityje.\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7556aa2 e-flex e-con-boxed e-con e-child\" data-id=\"7556aa2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-aa15b9d e-con-full e-flex e-con e-child\" data-id=\"aa15b9d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-64e3ef7 elementor-widget elementor-widget-spacer\" data-id=\"64e3ef7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7a169b6 elementor-widget elementor-widget-image\" data-id=\"7a169b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"17326\" data-permalink=\"https:\/\/masterbase.com\/lt\/mb\/crea-soluciones\/que-puedes-crear\/encarga-su-creacion\/graficas-06\/\" data-orig-file=\"https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/11\/graficas-06.png?fit=820%2C580&amp;ssl=1\" data-orig-size=\"820,580\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Flex Consulting\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/11\/graficas-06.png?fit=800%2C566&amp;ssl=1\" width=\"800\" height=\"566\" src=\"https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/11\/graficas-06.png?fit=800%2C566&amp;ssl=1\" class=\"attachment-large size-large wp-image-17326\" alt=\"&quot;Flex Consulting\" srcset=\"https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/11\/graficas-06.png?w=820&amp;ssl=1 820w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/11\/graficas-06.png?resize=300%2C212&amp;ssl=1 300w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/11\/graficas-06.png?resize=768%2C543&amp;ssl=1 768w, https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2024\/11\/graficas-06.png?resize=18%2C12&amp;ssl=1 18w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-92e70f1 e-con-full e-flex e-con e-child\" data-id=\"92e70f1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-db54546 e-flex e-con-boxed e-con e-child\" data-id=\"db54546\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d353113 elementor-widget elementor-widget-spacer\" data-id=\"d353113\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-61cda0d e-flex e-con-boxed e-con e-child\" data-id=\"61cda0d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-449cbfe elementor-widget elementor-widget-heading\" data-id=\"449cbfe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pertvarkykite savo versl\u0105 su \"Flex Consulting\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e4a57e2 elementor-widget elementor-widget-spacer\" data-id=\"e4a57e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ab074d1 elementor-widget elementor-widget-text-editor\" data-id=\"ab074d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>M\u016bs\u0173 konsultacij\u0173 pabaigoje ne tik optimizuosite savo procesus, bet ir b\u016bsite pasireng\u0119 toliau prisitaikyti prie nauj\u0173 technologini\u0173 tendencij\u0173.<\/p><p>Be to, kvie\u010diame susipa\u017einti su naujais \u012frankiais ir dalyvauti sesijose, kuriose skaitmenin\u0117s transformacijos lyderiai dalijasi savo strategijomis.<\/p><p><b>Prad\u0117kite keli\u0105 \u012f naujoves ir veiklos efektyvum\u0105 su \"Flex\" jau \u0161iandien. <\/b><b>Konsultacijos<\/b><b>. Kartu galime i\u0161\u0161\u016bkius paversti galimyb\u0117mis.<\/b><\/p><p>M\u016bs\u0173 raison d'\u00eatre - pad\u0117ti komandoms prad\u0117ti automatizavimo, inovacij\u0173 ir skaitmenin\u0117s transformacijos keli\u0105.<\/p><p>Tod\u0117l po \u0161io etapo kvie\u010diame jus daugiau su\u017einoti apie naujus automatizavimo \u012frankius, kurie i\u0161leid\u017eiami MasterBase\u00ae platformoje, ir dalyvauti internetin\u0117se sesijose, kuriose bus pristatomi \u012fvair\u016bs<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9768c71 e-flex e-con-boxed e-con e-parent\" data-id=\"9768c71\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f871a19 elementor-widget elementor-widget-spacer\" data-id=\"f871a19\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-46f4f65 elementor-widget elementor-widget-heading\" data-id=\"46f4f65\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Lanksti automatizavimo platforma. Pasirinkimas priklauso nuo j\u016bs\u0173.\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-104e515 elementor-widget elementor-widget-spacer\" data-id=\"104e515\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bb10775 e-grid e-con-boxed e-con e-parent\" data-id=\"bb10775\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-96d25ed elementor-cta--layout-image-above elementor-cta--tablet-layout-image-above elementor-cta--skin-classic elementor-animated-content elementor-widget elementor-widget-call-to-action\" data-id=\"96d25ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2025\/01\/automata-comb-1.png?fit=545%2C545&#038;ssl=1);\" role=\"img\" aria-label=\"Naudokite sprendimus\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tNaudokite sprendimus\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tKonfig\u016bruokite savo sprendimus naudodami m\u016bs\u0173 platform\u0105.\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t<a class=\"elementor-cta__button elementor-button elementor-size-\" href=\"https:\/\/masterbase.com\/lt\/wp-content\/es\/naudoti-sprendimus\/\" target=\"_blank\">\n\t\t\t\t\t\tSu\u017einokite daugiau\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f3a11bb elementor-cta--layout-image-above elementor-cta--tablet-layout-image-above elementor-cta--skin-classic elementor-animated-content elementor-widget elementor-widget-call-to-action\" data-id=\"f3a11bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2025\/01\/automata-comb-5.png?fit=545%2C545&#038;ssl=1);\" role=\"img\" aria-label=\"Sprendim\u0173 k\u016brimas\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tKurti sprendimus\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tKonfig\u016bruokite savo sprendimus naudodami m\u016bs\u0173 platform\u0105.\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t<a class=\"elementor-cta__button elementor-button elementor-size-\" href=\"https:\/\/masterbase.com\/lt\/wp-content\/es\/kuria-sprendimus\/\" target=\"_blank\">\n\t\t\t\t\t\tSu\u017einokite daugiau\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-54833c1 e-flex e-con-boxed e-con e-parent\" data-id=\"54833c1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-131f0b2 elementor-widget elementor-widget-spacer\" data-id=\"131f0b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Encarga su creaci\u00f3n Conf\u00eda la creaci\u00f3n de tus soluciones automatizadas a un Consultor experto. Contacta a un ejecutivo Encarga su creaci\u00f3n Conf\u00eda la creaci\u00f3n de tus soluciones automatizadas a un Consultor experto. Contacta un ejecutivo Encarga su creaci\u00f3n Optimiza tu negocio delegando la automatizaci\u00f3n a nuestros expertos de Flex Consulting En un entorno empresarial en [&hellip;]<\/p>\n","protected":false},"author":239642484,"featured_media":0,"parent":19789,"menu_order":314,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_crdt_document":"","footnotes":""},"class_list":["post-17074","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Encarga su creaci\u00f3n - MasterBase\u00ae<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/masterbase.com\/lt\/mb\/kuria-sprendimus\/galite-sukurti\/uzsako-jo-sukurima\/\" \/>\n<meta property=\"og:locale\" content=\"lt_LT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Encarga su creaci\u00f3n - MasterBase\u00ae\" \/>\n<meta property=\"og:description\" content=\"Encarga su creaci\u00f3n Conf\u00eda la creaci\u00f3n de tus soluciones automatizadas a un Consultor experto. Contacta a un ejecutivo Encarga su creaci\u00f3n Conf\u00eda la creaci\u00f3n de tus soluciones automatizadas a un Consultor experto. Contacta un ejecutivo Encarga su creaci\u00f3n Optimiza tu negocio delegando la automatizaci\u00f3n a nuestros expertos de Flex Consulting En un entorno empresarial en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/masterbase.com\/lt\/mb\/kuria-sprendimus\/galite-sukurti\/uzsako-jo-sukurima\/\" \/>\n<meta property=\"og:site_name\" content=\"MasterBase\u00ae\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-29T16:36:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/masterbase.com\/es\/es\/es\/wp-content\/uploads\/2025\/01\/automata-comb-3-1.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minut\u0117s\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/masterbase.com\\\/es\\\/mb\\\/crea-soluciones\\\/que-puedes-crear\\\/encarga-su-creacion\\\/\",\"url\":\"https:\\\/\\\/masterbase.com\\\/es\\\/mb\\\/crea-soluciones\\\/que-puedes-crear\\\/encarga-su-creacion\\\/\",\"name\":\"Encarga su creaci\u00f3n - MasterBase\u00ae\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/masterbase.com\\\/zh\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/masterbase.com\\\/es\\\/mb\\\/crea-soluciones\\\/que-puedes-crear\\\/encarga-su-creacion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/masterbase.com\\\/es\\\/mb\\\/crea-soluciones\\\/que-puedes-crear\\\/encarga-su-creacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/masterbase.com\\\/es\\\/es\\\/es\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/automata-comb-3-1.png\",\"datePublished\":\"2024-11-13T16:45:06+00:00\",\"dateModified\":\"2025-07-29T16:36:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/masterbase.com\\\/es\\\/mb\\\/crea-soluciones\\\/que-puedes-crear\\\/encarga-su-creacion\\\/#breadcrumb\"},\"inLanguage\":\"lt-LT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/masterbase.com\\\/es\\\/mb\\\/crea-soluciones\\\/que-puedes-crear\\\/encarga-su-creacion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"lt-LT\",\"@id\":\"https:\\\/\\\/masterbase.com\\\/es\\\/mb\\\/crea-soluciones\\\/que-puedes-crear\\\/encarga-su-creacion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/masterbase.com\\\/es\\\/es\\\/es\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/automata-comb-3-1.png\",\"contentUrl\":\"https:\\\/\\\/masterbase.com\\\/es\\\/es\\\/es\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/automata-comb-3-1.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/masterbase.com\\\/es\\\/mb\\\/crea-soluciones\\\/que-puedes-crear\\\/encarga-su-creacion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/masterbase.com\\\/da\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MasterBase\u00ae Aut\u00f3matas que trabajan para ti\",\"item\":\"https:\\\/\\\/masterbase.com\\\/da\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Crea Soluciones de automatizaci\u00f3n\",\"item\":\"https:\\\/\\\/masterbase.com\\\/it\\\/mb\\\/crea-soluzioni\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Que puedes crear\",\"item\":\"https:\\\/\\\/masterbase.com\\\/sl\\\/mb\\\/crea-soluciones\\\/que-puedes-crear\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Encarga su creaci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/masterbase.com\\\/zh\\\/#website\",\"url\":\"https:\\\/\\\/masterbase.com\\\/zh\\\/\",\"name\":\"MasterBase\u00ae\",\"description\":\"Automatas that work for you\",\"publisher\":{\"@id\":\"https:\\\/\\\/masterbase.com\\\/zh\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/masterbase.com\\\/zh\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"lt-LT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/masterbase.com\\\/zh\\\/#organization\",\"name\":\"MasterBase\u00ae\",\"url\":\"https:\\\/\\\/masterbase.com\\\/zh\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"lt-LT\",\"@id\":\"https:\\\/\\\/masterbase.com\\\/zh\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/masterbase.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Logo_negro_sinslogan.png?fit=1476%2C972&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/masterbase.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Logo_negro_sinslogan.png?fit=1476%2C972&ssl=1\",\"width\":1476,\"height\":972,\"caption\":\"MasterBase\u00ae\"},\"image\":{\"@id\":\"https:\\\/\\\/masterbase.com\\\/zh\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"U\u017esisakykite savo k\u016brin\u012f - MasterBase\u00ae","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/masterbase.com\/lt\/mb\/kuria-sprendimus\/galite-sukurti\/uzsako-jo-sukurima\/","og_locale":"lt_LT","og_type":"article","og_title":"Encarga su creaci\u00f3n - MasterBase\u00ae","og_description":"Encarga su creaci\u00f3n Conf\u00eda la creaci\u00f3n de tus soluciones automatizadas a un Consultor experto. Contacta a un ejecutivo Encarga su creaci\u00f3n Conf\u00eda la creaci\u00f3n de tus soluciones automatizadas a un Consultor experto. Contacta un ejecutivo Encarga su creaci\u00f3n Optimiza tu negocio delegando la automatizaci\u00f3n a nuestros expertos de Flex Consulting En un entorno empresarial en [&hellip;]","og_url":"https:\/\/masterbase.com\/lt\/mb\/kuria-sprendimus\/galite-sukurti\/uzsako-jo-sukurima\/","og_site_name":"MasterBase\u00ae","article_modified_time":"2025-07-29T16:36:36+00:00","og_image":[{"url":"https:\/\/masterbase.com\/es\/es\/es\/wp-content\/uploads\/2025\/01\/automata-comb-3-1.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minut\u0117s"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/masterbase.com\/es\/mb\/crea-soluciones\/que-puedes-crear\/encarga-su-creacion\/","url":"https:\/\/masterbase.com\/es\/mb\/crea-soluciones\/que-puedes-crear\/encarga-su-creacion\/","name":"U\u017esisakykite savo k\u016brin\u012f - MasterBase\u00ae","isPartOf":{"@id":"https:\/\/masterbase.com\/zh\/#website"},"primaryImageOfPage":{"@id":"https:\/\/masterbase.com\/es\/mb\/crea-soluciones\/que-puedes-crear\/encarga-su-creacion\/#primaryimage"},"image":{"@id":"https:\/\/masterbase.com\/es\/mb\/crea-soluciones\/que-puedes-crear\/encarga-su-creacion\/#primaryimage"},"thumbnailUrl":"https:\/\/masterbase.com\/es\/es\/es\/wp-content\/uploads\/2025\/01\/automata-comb-3-1.png","datePublished":"2024-11-13T16:45:06+00:00","dateModified":"2025-07-29T16:36:36+00:00","breadcrumb":{"@id":"https:\/\/masterbase.com\/es\/mb\/crea-soluciones\/que-puedes-crear\/encarga-su-creacion\/#breadcrumb"},"inLanguage":"lt-LT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/masterbase.com\/es\/mb\/crea-soluciones\/que-puedes-crear\/encarga-su-creacion\/"]}]},{"@type":"ImageObject","inLanguage":"lt-LT","@id":"https:\/\/masterbase.com\/es\/mb\/crea-soluciones\/que-puedes-crear\/encarga-su-creacion\/#primaryimage","url":"https:\/\/masterbase.com\/es\/es\/es\/wp-content\/uploads\/2025\/01\/automata-comb-3-1.png","contentUrl":"https:\/\/masterbase.com\/es\/es\/es\/wp-content\/uploads\/2025\/01\/automata-comb-3-1.png"},{"@type":"BreadcrumbList","@id":"https:\/\/masterbase.com\/es\/mb\/crea-soluciones\/que-puedes-crear\/encarga-su-creacion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/masterbase.com\/da\/"},{"@type":"ListItem","position":2,"name":"MasterBase\u00ae Aut\u00f3matas que trabajan para ti","item":"https:\/\/masterbase.com\/da\/"},{"@type":"ListItem","position":3,"name":"Crea Soluciones de automatizaci\u00f3n","item":"https:\/\/masterbase.com\/it\/mb\/crea-soluzioni\/"},{"@type":"ListItem","position":4,"name":"Que puedes crear","item":"https:\/\/masterbase.com\/sl\/mb\/crea-soluciones\/que-puedes-crear\/"},{"@type":"ListItem","position":5,"name":"Encarga su creaci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/masterbase.com\/zh\/#website","url":"https:\/\/masterbase.com\/zh\/","name":"MasterBase\u00ae","description":"Automatai, kurie dirba jums","publisher":{"@id":"https:\/\/masterbase.com\/zh\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/masterbase.com\/zh\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"lt-LT"},{"@type":"Organization","@id":"https:\/\/masterbase.com\/zh\/#organization","name":"MasterBase\u00ae","url":"https:\/\/masterbase.com\/zh\/","logo":{"@type":"ImageObject","inLanguage":"lt-LT","@id":"https:\/\/masterbase.com\/zh\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2023\/09\/Logo_negro_sinslogan.png?fit=1476%2C972&ssl=1","contentUrl":"https:\/\/i0.wp.com\/masterbase.com\/wp-content\/uploads\/2023\/09\/Logo_negro_sinslogan.png?fit=1476%2C972&ssl=1","width":1476,"height":972,"caption":"MasterBase\u00ae"},"image":{"@id":"https:\/\/masterbase.com\/zh\/#\/schema\/logo\/image\/"}}]}},"jetpack_likes_enabled":false,"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/Pf6Ilf-4ro","_links":{"self":[{"href":"https:\/\/masterbase.com\/lt\/wp-json\/wp\/v2\/pages\/17074","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/masterbase.com\/lt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/masterbase.com\/lt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/masterbase.com\/lt\/wp-json\/wp\/v2\/users\/239642484"}],"replies":[{"embeddable":true,"href":"https:\/\/masterbase.com\/lt\/wp-json\/wp\/v2\/comments?post=17074"}],"version-history":[{"count":100,"href":"https:\/\/masterbase.com\/lt\/wp-json\/wp\/v2\/pages\/17074\/revisions"}],"predecessor-version":[{"id":23000,"href":"https:\/\/masterbase.com\/lt\/wp-json\/wp\/v2\/pages\/17074\/revisions\/23000"}],"up":[{"embeddable":true,"href":"https:\/\/masterbase.com\/lt\/wp-json\/wp\/v2\/pages\/19789"}],"wp:attachment":[{"href":"https:\/\/masterbase.com\/lt\/wp-json\/wp\/v2\/media?parent=17074"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}